










{"id":345394,"date":"2026-09-02T12:00:23","date_gmt":"2026-09-02T10:00:23","guid":{"rendered":"https:\/\/www.myastreet.com\/?post_type=product&#038;p=345394"},"modified":"2026-09-02T14:18:13","modified_gmt":"2026-09-02T12:18:13","slug":"lm81787-06-pantalone","status":"publish","type":"product","link":"https:\/\/www.myastreet.com\/es\/prodotti\/lm81787-06-pantalone\/","title":{"rendered":"PANTALONI IN TESSUTO A SIGARETTA"},"content":{"rendered":"<p data-start=\"85\" data-end=\"506\">Pantaloni da donna a sigaretta in tessuto comfort, ideali per un look elegante e contemporaneo. La linea affusolata valorizza la silhouette, mentre il tessuto morbido e piacevole da indossare assicura comfort e libert\u00e0 di movimento per tutta la giornata. Perfetti da abbinare a blazer, camicie, maglie o top, sono un capo versatile adatto all&#8217;ufficio, al tempo libero e alle occasioni pi\u00f9 ricercate.<\/p>\n<p>&nbsp;<\/p>\n<p>Composizione: 95%POLIESTERE 5%SPANDEX MADE IN ITALY 62045300<br \/>\nStagione: AUTUNNO 2026<br \/>\nOrigine: MADE IN ITALY<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pantaloni da donna a sigaretta in tessuto comfort, ideali per un look elegante e contemporaneo. La linea affusolata valorizza la silhouette, mentre il tessuto morbido e piacevole da indossare assicura comfort e libert\u00e0 di movimento per tutta la giornata. Perfetti da abbinare a blazer, camicie, maglie o top, sono un capo versatile adatto all&#8217;ufficio, al [&#8230;]\n","protected":false},"featured_media":351473,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[2795,2799],"product_tag":[],"class_list":["post-345394","product","type-product","status-publish","has-post-thumbnail","product_cat-a26","product_cat-a26-pantaloni","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product\/345394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media\/351473"}],"wp:attachment":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media?parent=345394"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_brand?post=345394"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_cat?post=345394"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_tag?post=345394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}