










{"id":335113,"date":"2026-09-02T10:15:40","date_gmt":"2026-09-02T08:15:40","guid":{"rendered":"https:\/\/www.myastreet.com\/?post_type=product&#038;p=335113"},"modified":"2026-09-02T13:16:37","modified_gmt":"2026-09-02T11:16:37","slug":"mn11557-06-maglia","status":"publish","type":"product","link":"https:\/\/www.myastreet.com\/es\/prodotti\/mn11557-06-maglia\/","title":{"rendered":"MAGLIONE JACQUARD CON FRANGE"},"content":{"rendered":"<p>Originale e ricco di personalit\u00e0, questo maglione jacquard da donna con frange \u00e8 il capo ideale per chi ama uno stile ricercato e contemporaneo. La lavorazione fantasia jacquard \u00e8 impreziosita da dettagli sfrangiati che donano movimento e carattere al design, creando un effetto distintivo e di tendenza. La vestibilit\u00e0 confortevole lo rende perfetto da abbinare a jeans, pantaloni o gonne per realizzare look casual chic dal fascino boho e moderno. Un modello che unisce comfort, creativit\u00e0 e stile.<\/p>\n<p>&nbsp;<\/p>\n<p>Composizione: 65%ACRILICO 14%NYLON 9%VISCOSA 9%LANA 3%POLIAMMIDE MADE IN ITALY 61103099<br \/>\nStagione: AUTUNNO 2026<br \/>\nOrigine: MADE IN ITALY<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Originale e ricco di personalit\u00e0, questo maglione jacquard da donna con frange \u00e8 il capo ideale per chi ama uno stile ricercato e contemporaneo. La lavorazione fantasia jacquard \u00e8 impreziosita da dettagli sfrangiati che donano movimento e carattere al design, creando un effetto distintivo e di tendenza. La vestibilit\u00e0 confortevole lo rende perfetto da abbinare [&#8230;]\n","protected":false},"featured_media":343617,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[2795,2800,1264],"product_tag":[],"class_list":["post-335113","product","type-product","status-publish","has-post-thumbnail","product_cat-a26","product_cat-a26-maglie","product_cat-semiprogrammato","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product\/335113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media\/343617"}],"wp:attachment":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media?parent=335113"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_brand?post=335113"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_cat?post=335113"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_tag?post=335113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}