










{"id":294807,"date":"2025-11-07T06:00:13","date_gmt":"2025-11-07T05:00:13","guid":{"rendered":"https:\/\/www.myastreet.com\/?post_type=product&#038;p=294807"},"modified":"2026-02-11T14:17:31","modified_gmt":"2026-02-11T13:17:31","slug":"ml8778-90-maglia","status":"publish","type":"product","link":"https:\/\/www.myastreet.com\/es\/prodotti\/ml8778-90-maglia\/","title":{"rendered":"MAGLIA \u201cMESS AGE\u201d CON RICAMO IN RILIEVO"},"content":{"rendered":"<p>Maglia girocollo in maglia fine con scritta ricamata in rilievo \u201cMess Age\u201d. Il design minimal \u00e8 arricchito dal lettering a contrasto che dona un tocco moderno e deciso al look. Un capo casual-chic ideale per creare outfit dal carattere contemporaneo, perfetto da abbinare sia a pantaloni sartoriali che a denim per un\u2019eleganza disinvolta.<\/p>\n<p>Composizione: 45%VISCOSA 28%POLIESTERE 27%POLIAMMIDE MADE IN PRC<br \/>\nStagione: INVERNO 2025<br \/>\nOrigine: IDEATO IN ITALIA MADE IN PRC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maglia girocollo in maglia fine con scritta ricamata in rilievo \u201cMess Age\u201d. Il design minimal \u00e8 arricchito dal lettering a contrasto che dona un tocco moderno e deciso al look. Un capo casual-chic ideale per creare outfit dal carattere contemporaneo, perfetto da abbinare sia a pantaloni sartoriali che a denim per un\u2019eleganza disinvolta. Composizione: 45%VISCOSA [&#8230;]\n","protected":false},"featured_media":296167,"template":"","meta":{"content-type":""},"product_brand":[],"product_cat":[1383,1448,1479,1384,1392,2536],"product_tag":[],"class_list":{"0":"post-294807","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-a25","7":"product_cat-i25","8":"product_cat-maglie-i25","9":"product_cat-maglie-a25","10":"product_cat-maglieria-a25","11":"product_cat-xmas-sale","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-variable"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product\/294807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media\/296167"}],"wp:attachment":[{"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/media?parent=294807"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_brand?post=294807"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_cat?post=294807"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.myastreet.com\/es\/wp-json\/wp\/v2\/product_tag?post=294807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}